{"id":10609,"date":"2024-04-12T10:48:40","date_gmt":"2024-04-12T08:48:40","guid":{"rendered":"https:\/\/staging.accentform.com\/?post_type=services&#038;p=10609"},"modified":"2024-04-25T12:58:17","modified_gmt":"2024-04-25T10:58:17","slug":"rauten-gfk-kunstwerk-fuer-audi","status":"publish","type":"services","link":"https:\/\/accentform.com\/de\/referenzen\/rauten-gfk-kunstwerk-fuer-audi\/","title":{"rendered":"Rautenkunstwerk f\u00fcr Audi"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><em>GFK-Kunstwerk f\u00fcr Audi auf der Design Miami\/ 2013<\/em><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der Stand von Audi auf der Design Miami\/ 2013 steht ganz im Zeichen von Audi Sport. Zwei Supersportwagen stehen gut ausgeleuchtet vor der von uns gefertigten roten Rautenkulisse. Das dreidimensionale Kunstwerk aus GFK stellt mittels das Logo von Audi Sport darstellen<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Kunstwerk besteht aus etwa 30 Rauten in den verschiedensten Gr\u00f6\u00dfen, von 50 x 74 cm bis hin zu \u00fcber 2,40m x 2,07m Au\u00dfenfl\u00e4che. Sie bestehen aus GFK Laminat mit Sandwich Anlagen f\u00fcr eine verbesserte Steifigkeit. In den von uns produzierten Holzformen wurden jeweils eine Raute mit Seitenw\u00e4nden und ein Deckel hergestellt, diese wurden sp\u00e4ter zusammengef\u00fcgt und nahtlos verspachtelt.<\/p>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\">Alle samt Hochglanzlackiert im typischen Audi Sport \u2013<strong>&nbsp;ROT<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"10611\" src=\"https:\/\/accentform.com\/wp-content\/uploads\/2024\/03\/img-7498-IM-1024x683.jpg\" alt=\"Lackierung des GFK Kunstwerks\" class=\"wp-image-10611\" srcset=\"https:\/\/accentform.com\/wp-content\/uploads\/2024\/03\/img-7498-IM-1024x683.jpg 1024w, https:\/\/accentform.com\/wp-content\/uploads\/2024\/03\/img-7498-IM-300x200.jpg 300w, https:\/\/accentform.com\/wp-content\/uploads\/2024\/03\/img-7498-IM-768x512.jpg 768w, https:\/\/accentform.com\/wp-content\/uploads\/2024\/03\/img-7498-IM-1536x1024.jpg 1536w, https:\/\/accentform.com\/wp-content\/uploads\/2024\/03\/img-7498-IM.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"10612\" src=\"https:\/\/accentform.com\/wp-content\/uploads\/2024\/03\/img-7465-IM-683x1024.jpg\" alt=\"Lackierung der GFK Kunstwerk\" class=\"wp-image-10612\" srcset=\"https:\/\/accentform.com\/wp-content\/uploads\/2024\/03\/img-7465-IM-683x1024.jpg 683w, https:\/\/accentform.com\/wp-content\/uploads\/2024\/03\/img-7465-IM-200x300.jpg 200w, https:\/\/accentform.com\/wp-content\/uploads\/2024\/03\/img-7465-IM-768x1152.jpg 768w, https:\/\/accentform.com\/wp-content\/uploads\/2024\/03\/img-7465-IM-1024x1536.jpg 1024w, https:\/\/accentform.com\/wp-content\/uploads\/2024\/03\/img-7465-IM.jpg 1280w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Die dreidimensionale Installation spielt mit der Raute, dem Symbol von Audi Sport. Die Rauten wurden an die Wand geh\u00e4ngt, miteinander zu einer S\u00e4ule verklebt und von der Decke abgeh\u00e4ngt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Herausforderungen bei diesem Projekt bestanden f\u00fcr uns in der Komplexit\u00e4t des Gebildes und in der Oberfl\u00e4chenbearbeitung der Rauten. Die Oberfl\u00e4chen wurden alle mit Spiegelglanz hergestellt, was ein extrem hohes Ma\u00df an Sorgfalt forderte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ebenfalls fertigten wir sehr solide Transportgestelle, die Luft- und Seefrachttauglich waren um die empfindlichen Oberfl\u00e4chen w\u00e4hrend des Transports zu sch\u00fctzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir konnten die vom Kunden gew\u00fcnschten Oberfl\u00e4chen in Perfektion erzielen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir arbeiteten eng an der Seite des Kunden und m\u00f6chten uns f\u00fcr die gute Zusammenarbeit bei der\u00a0<a href=\"http:\/\/de.expotechnik.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Expotechnik GmbH<\/strong><\/a>\u00a0bedanken.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Projektdetails zum dem GFK-Kunstwerk<\/h2>\n\n\n\n<div class=\"wp-block-accentform-project-data\">\n<div class=\"wp-block-accentform-project-detail\">\n<h3 class=\"wp-block-heading\">Kunde<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.etglobal.com\/de\/\"><strong>Expotechnik GmbH<\/strong><\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-accentform-project-detail\">\n<h3 class=\"wp-block-heading\">Abmessungen\/Gewicht<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">ca. 30 Rauten, 10\u201370kg, bis rund 2,50m<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-accentform-project-detail\">\n<h2 class=\"wp-block-heading\">Standort:<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Miami Beach (Florida, USA)<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-accentform-project-detail\">\n<h3 class=\"wp-block-heading\">Projektnummer<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">P20-13<\/p>\n<\/div>\n<\/div>\n","protected":false},"featured_media":10610,"template":"","manufacturing-cat":[],"services-categories":[50],"class_list":["post-10609","services","type-services","status-publish","has-post-thumbnail","hentry","services-categories-messe-und-ausstellungsbau"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rauten-Kunstwerk aus GFK f\u00fcr Audi - ACCENTFORM<\/title>\n<meta name=\"description\" content=\"Das Kunstwerk besteht aus etwa 30 Rauten in den verschiedensten Gr\u00f6\u00dfen aus GFK Laminat mit Sandwich Anlagen f\u00fcr eine verbesserte Steifigkeit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accentform.com\/de\/referenzen\/rauten-gfk-kunstwerk-fuer-audi\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rauten-Kunstwerk aus GFK f\u00fcr Audi - ACCENTFORM\" \/>\n<meta property=\"og:description\" content=\"Das Kunstwerk besteht aus etwa 30 Rauten in den verschiedensten Gr\u00f6\u00dfen aus GFK Laminat mit Sandwich Anlagen f\u00fcr eine verbesserte Steifigkeit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accentform.com\/de\/referenzen\/rauten-gfk-kunstwerk-fuer-audi\/\" \/>\n<meta property=\"og:site_name\" content=\"ACCENTFORM\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-25T10:58:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accentform.com\/wp-content\/uploads\/2024\/03\/banner-audi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rauten-Kunstwerk aus GFK f\u00fcr Audi - ACCENTFORM","description":"Das Kunstwerk besteht aus etwa 30 Rauten in den verschiedensten Gr\u00f6\u00dfen aus GFK Laminat mit Sandwich Anlagen f\u00fcr eine verbesserte Steifigkeit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accentform.com\/de\/referenzen\/rauten-gfk-kunstwerk-fuer-audi\/","og_locale":"de_DE","og_type":"article","og_title":"Rauten-Kunstwerk aus GFK f\u00fcr Audi - ACCENTFORM","og_description":"Das Kunstwerk besteht aus etwa 30 Rauten in den verschiedensten Gr\u00f6\u00dfen aus GFK Laminat mit Sandwich Anlagen f\u00fcr eine verbesserte Steifigkeit.","og_url":"https:\/\/accentform.com\/de\/referenzen\/rauten-gfk-kunstwerk-fuer-audi\/","og_site_name":"ACCENTFORM","article_modified_time":"2024-04-25T10:58:17+00:00","og_image":[{"width":1170,"height":433,"url":"https:\/\/accentform.com\/wp-content\/uploads\/2024\/03\/banner-audi.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/accentform.com\/de\/referenzen\/rauten-gfk-kunstwerk-fuer-audi\/","url":"https:\/\/accentform.com\/de\/referenzen\/rauten-gfk-kunstwerk-fuer-audi\/","name":"Rauten-Kunstwerk aus GFK f\u00fcr Audi - ACCENTFORM","isPartOf":{"@id":"https:\/\/accentform.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accentform.com\/de\/referenzen\/rauten-gfk-kunstwerk-fuer-audi\/#primaryimage"},"image":{"@id":"https:\/\/accentform.com\/de\/referenzen\/rauten-gfk-kunstwerk-fuer-audi\/#primaryimage"},"thumbnailUrl":"https:\/\/accentform.com\/wp-content\/uploads\/2024\/03\/banner-audi.jpg","datePublished":"2024-04-12T08:48:40+00:00","dateModified":"2024-04-25T10:58:17+00:00","description":"Das Kunstwerk besteht aus etwa 30 Rauten in den verschiedensten Gr\u00f6\u00dfen aus GFK Laminat mit Sandwich Anlagen f\u00fcr eine verbesserte Steifigkeit.","breadcrumb":{"@id":"https:\/\/accentform.com\/de\/referenzen\/rauten-gfk-kunstwerk-fuer-audi\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accentform.com\/de\/referenzen\/rauten-gfk-kunstwerk-fuer-audi\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/accentform.com\/de\/referenzen\/rauten-gfk-kunstwerk-fuer-audi\/#primaryimage","url":"https:\/\/accentform.com\/wp-content\/uploads\/2024\/03\/banner-audi.jpg","contentUrl":"https:\/\/accentform.com\/wp-content\/uploads\/2024\/03\/banner-audi.jpg","width":1170,"height":433},{"@type":"BreadcrumbList","@id":"https:\/\/accentform.com\/de\/referenzen\/rauten-gfk-kunstwerk-fuer-audi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/accentform.com\/de\/"},{"@type":"ListItem","position":2,"name":"Referenzen","item":"https:\/\/accentform.com\/de\/referenzen\/"},{"@type":"ListItem","position":3,"name":"Rautenkunstwerk f\u00fcr Audi"}]},{"@type":"WebSite","@id":"https:\/\/accentform.com\/de\/#website","url":"https:\/\/accentform.com\/de\/","name":"ACCENTFORM","description":"","publisher":{"@id":"https:\/\/accentform.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accentform.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/accentform.com\/de\/#organization","name":"ACCENTFORM","url":"https:\/\/accentform.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/accentform.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/accentform.com\/wp-content\/uploads\/2023\/06\/Logo500px.png","contentUrl":"https:\/\/accentform.com\/wp-content\/uploads\/2023\/06\/Logo500px.png","width":500,"height":44,"caption":"ACCENTFORM"},"image":{"@id":"https:\/\/accentform.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/accentform.com\/de\/wp-json\/wp\/v2\/services\/10609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accentform.com\/de\/wp-json\/wp\/v2\/services"}],"about":[{"href":"https:\/\/accentform.com\/de\/wp-json\/wp\/v2\/types\/services"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accentform.com\/de\/wp-json\/wp\/v2\/media\/10610"}],"wp:attachment":[{"href":"https:\/\/accentform.com\/de\/wp-json\/wp\/v2\/media?parent=10609"}],"wp:term":[{"taxonomy":"manufacturing-cat","embeddable":true,"href":"https:\/\/accentform.com\/de\/wp-json\/wp\/v2\/manufacturing-cat?post=10609"},{"taxonomy":"services-categories","embeddable":true,"href":"https:\/\/accentform.com\/de\/wp-json\/wp\/v2\/services-categories?post=10609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}